{"id":15751,"date":"2025-08-14T17:44:26","date_gmt":"2025-08-14T15:44:26","guid":{"rendered":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80.jpg"},"modified":"2025-08-14T17:44:26","modified_gmt":"2025-08-14T15:44:26","slug":"wand-deckenmalerei-80-2","status":"inherit","type":"attachment","link":"https:\/\/welterbewestwerkcorvey.de\/en\/wand-deckenmalerei-80-2\/","title":{"rendered":"wand-deckenmalerei-80"},"author":1,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":[],"class_list":["post-15751","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>wand-deckenmalerei-80 - Welterbe Westwerk Corvey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/welterbewestwerkcorvey.de\/en\/wand-deckenmalerei-80-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"wand-deckenmalerei-80 - Welterbe Westwerk Corvey\" \/>\n<meta property=\"og:url\" content=\"https:\/\/welterbewestwerkcorvey.de\/en\/wand-deckenmalerei-80-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Welterbe Westwerk Corvey\" \/>\n<meta property=\"og:image\" content=\"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/wand-deckenmalerei-80-2\\\/\",\"url\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/wand-deckenmalerei-80-2\\\/\",\"name\":\"wand-deckenmalerei-80 - Welterbe Westwerk Corvey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/#website\"},\"datePublished\":\"2025-08-14T15:44:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/wand-deckenmalerei-80-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/wand-deckenmalerei-80-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/wand-deckenmalerei-80-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"wand-deckenmalerei-80\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/\",\"name\":\"Welterbe Westwerk Corvey\",\"description\":\"Weltgeschichte am Weserbogen\",\"publisher\":{\"@id\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/#organization\",\"name\":\"Pfarrverbund Corvey\",\"url\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/wp-content\\\/uploads\\\/signet-wwc-corvey-rgb-1.png\",\"contentUrl\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/wp-content\\\/uploads\\\/signet-wwc-corvey-rgb-1.png\",\"width\":791,\"height\":1181,\"caption\":\"Pfarrverbund Corvey\"},\"image\":{\"@id\":\"https:\\\/\\\/welterbewestwerkcorvey.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"wand-deckenmalerei-80 - Welterbe Westwerk Corvey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/welterbewestwerkcorvey.de\/en\/wand-deckenmalerei-80-2\/","og_locale":"en_US","og_type":"article","og_title":"wand-deckenmalerei-80 - Welterbe Westwerk Corvey","og_url":"https:\/\/welterbewestwerkcorvey.de\/en\/wand-deckenmalerei-80-2\/","og_site_name":"Welterbe Westwerk Corvey","og_image":[{"width":2160,"height":1350,"url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/welterbewestwerkcorvey.de\/en\/wand-deckenmalerei-80-2\/","url":"https:\/\/welterbewestwerkcorvey.de\/en\/wand-deckenmalerei-80-2\/","name":"wand-deckenmalerei-80 - Welterbe Westwerk Corvey","isPartOf":{"@id":"https:\/\/welterbewestwerkcorvey.de\/en\/#website"},"datePublished":"2025-08-14T15:44:26+00:00","breadcrumb":{"@id":"https:\/\/welterbewestwerkcorvey.de\/en\/wand-deckenmalerei-80-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/welterbewestwerkcorvey.de\/en\/wand-deckenmalerei-80-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/welterbewestwerkcorvey.de\/en\/wand-deckenmalerei-80-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/welterbewestwerkcorvey.de\/en\/"},{"@type":"ListItem","position":2,"name":"wand-deckenmalerei-80"}]},{"@type":"WebSite","@id":"https:\/\/welterbewestwerkcorvey.de\/en\/#website","url":"https:\/\/welterbewestwerkcorvey.de\/en\/","name":"Welterbe Westwerk Corvey","description":"Weltgeschichte am Weserbogen","publisher":{"@id":"https:\/\/welterbewestwerkcorvey.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/welterbewestwerkcorvey.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/welterbewestwerkcorvey.de\/en\/#organization","name":"Pfarrverbund Corvey","url":"https:\/\/welterbewestwerkcorvey.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/welterbewestwerkcorvey.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/signet-wwc-corvey-rgb-1.png","contentUrl":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/signet-wwc-corvey-rgb-1.png","width":791,"height":1181,"caption":"Pfarrverbund Corvey"},"image":{"@id":"https:\/\/welterbewestwerkcorvey.de\/en\/#\/schema\/logo\/image\/"}}]}},"smush":"Not processed","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80.jpg\" rel=\"prettyPhoto[gallery-BCrT]\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"300\" src=\"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-480x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-480x300.jpg 480w, https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-1024x640.jpg 1024w, https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-768x480.jpg 768w, https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-1536x960.jpg 1536w, https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-2048x1280.jpg 2048w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2160,"height":1350,"file":"wand-deckenmalerei-80.jpg","filesize":262610,"sizes":{"medium":{"file":"wand-deckenmalerei-80-480x300.jpg","width":480,"height":300,"filesize":27309,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-480x300.jpg"},"large":{"file":"wand-deckenmalerei-80-1024x640.jpg","width":1024,"height":640,"filesize":125901,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-1024x640.jpg"},"thumbnail":{"file":"wand-deckenmalerei-80-240x240.jpg","width":240,"height":240,"filesize":13900,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-240x240.jpg"},"medium_large":{"file":"wand-deckenmalerei-80-768x480.jpg","width":768,"height":480,"filesize":69533,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-768x480.jpg"},"1536x1536":{"file":"wand-deckenmalerei-80-1536x960.jpg","width":1536,"height":960,"filesize":273402,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-1536x960.jpg"},"2048x2048":{"file":"wand-deckenmalerei-80-2048x1280.jpg","width":2048,"height":1280,"filesize":445235,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-2048x1280.jpg"},"portfolio-thumb":{"file":"wand-deckenmalerei-80-600x403.jpg","width":600,"height":403,"filesize":46954,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-600x403.jpg"},"nectar_small_square":{"file":"wand-deckenmalerei-80-140x140.jpg","width":140,"height":140,"filesize":5559,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-140x140.jpg"},"portfolio-thumb_large":{"file":"wand-deckenmalerei-80-900x604.jpg","width":900,"height":604,"filesize":106959,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-900x604.jpg"},"portfolio-thumb_small":{"file":"wand-deckenmalerei-80-400x269.jpg","width":400,"height":269,"filesize":20862,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-400x269.jpg"},"portfolio-widget":{"file":"wand-deckenmalerei-80-100x100.jpg","width":100,"height":100,"filesize":3318,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-100x100.jpg"},"wide":{"file":"wand-deckenmalerei-80-1000x500.jpg","width":1000,"height":500,"filesize":95859,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-1000x500.jpg"},"wide_photography":{"file":"wand-deckenmalerei-80-900x600.jpg","width":900,"height":600,"filesize":105759,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-900x600.jpg"},"wide_small":{"file":"wand-deckenmalerei-80-670x335.jpg","width":670,"height":335,"filesize":41815,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-670x335.jpg"},"regular":{"file":"wand-deckenmalerei-80-500x500.jpg","width":500,"height":500,"filesize":59064,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-500x500.jpg"},"regular_small":{"file":"wand-deckenmalerei-80-350x350.jpg","width":350,"height":350,"filesize":28913,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-350x350.jpg"},"tall":{"file":"wand-deckenmalerei-80-500x1000.jpg","width":500,"height":1000,"filesize":147637,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-500x1000.jpg"},"wide_tall":{"file":"wand-deckenmalerei-80-1000x1000.jpg","width":1000,"height":1000,"filesize":217849,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-1000x1000.jpg"},"large_featured":{"file":"wand-deckenmalerei-80-1870x770.jpg","width":1870,"height":770,"filesize":254396,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-1870x770.jpg"},"medium_featured":{"file":"wand-deckenmalerei-80-800x800.jpg","width":800,"height":800,"filesize":145956,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80-800x800.jpg"},"full":{"file":"wand-deckenmalerei-80.jpg","width":2160,"height":1350,"mime_type":"image\/jpeg","source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80.jpg"}},"image_meta":{"aperture":"4","credit":"","camera":"ILCE-6500","caption":"","created_timestamp":"1499870847","copyright":"","focal_length":"43","iso":"6400","shutter_speed":"0.0125","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/welterbewestwerkcorvey.de\/wp-content\/uploads\/wand-deckenmalerei-80.jpg","_links":{"self":[{"href":"https:\/\/welterbewestwerkcorvey.de\/en\/wp-json\/wp\/v2\/media\/15751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welterbewestwerkcorvey.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/welterbewestwerkcorvey.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/welterbewestwerkcorvey.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/welterbewestwerkcorvey.de\/en\/wp-json\/wp\/v2\/comments?post=15751"}]}}